{"id":10959,"count":31,"description":"<strong>Trasforma i tuoi tavoli con le nostre belle tovaglie!<\/strong>\nScopri la nostra selezione di <strong>tovaglie<\/strong> progettate per esaltare i tuoi eventi e la tua quotidianit\u00e0. Goditi l'eleganza intramontabile delle <strong>tovaglie damascate<\/strong>, perfette per aggiungere un tocco raffinato ai tuoi tavoli grazie alla loro texture morbida e ai loro motivi eleganti.  Opta per la praticit\u00e0 e la modernit\u00e0 con le nostre <strong>tovaglie in TNT<\/strong>, leggere, resistenti e ideali per un uso singolo o riutilizzabile a seconda delle tue esigenze.\n\nFacili da posare e disponibili in una variet\u00e0 di colori e formati, ti offrono la soluzione perfetta per tutte le tue esigenze di decorazione della tavola, che si tratti di pranzi in famiglia, matrimoni o eventi professionali.\n\n<strong>Valorizza ogni momento con un tavolo perfettamente vestito.<\/strong>","link":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/","name":"Tovaglie","slug":"tovaglie","taxonomy":"product_cat","parent":10406,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tovaglie - Damascate \/ TNT - CSJ Imballaggi<\/title>\n<meta name=\"description\" content=\"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Tovaglie\" \/>\n<meta property=\"og:description\" content=\"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/\",\"name\":\"Tovaglie - Damascate \/ TNT - CSJ Imballaggi\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\"},\"description\":\"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imballaggi alimentari\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ristorazione\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tovaglioli \/ set da tavola \/ tovaglie\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Tovaglie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tovaglie - Damascate \/ TNT - CSJ Imballaggi","description":"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/","og_locale":"it_IT","og_type":"article","og_title":"Archives des Tovaglie","og_description":"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.","og_url":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/","og_site_name":"CSJ Emballages","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/","url":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/","name":"Tovaglie - Damascate \/ TNT - CSJ Imballaggi","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/it\/#website"},"description":"Scoprite le nostre tovaglie damascate e in TNT in rotoli, disponibili in diversi colori per decorare con eleganza tavoli, buffet e ricevimenti.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/tovaglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/"},{"@type":"ListItem","position":2,"name":"Imballaggi alimentari","item":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/"},{"@type":"ListItem","position":3,"name":"Ristorazione","item":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/"},{"@type":"ListItem","position":4,"name":"Tovaglioli \/ set da tavola \/ tovaglie","item":"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/tovaglioli-set-da-tavola-tovaglie\/"},{"@type":"ListItem","position":5,"name":"Tovaglie"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/it\/#website","url":"https:\/\/www.csj-emballages.com\/it\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/it\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Nappe-intissee-taupe-png.webp","_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat\/10959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat\/10406"}],"wp:post_type":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product?product_cat=10959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}