{"id":271625,"date":"2024-11-21T02:18:20","date_gmt":"2024-11-21T01:18:20","guid":{"rendered":"https:\/\/www.csj-emballages.com\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/"},"modified":"2026-08-29T02:12:44","modified_gmt":"2026-08-29T00:12:44","slug":"cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50","status":"publish","type":"product","link":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/","title":{"rendered":"Cannuccia Bubble Tea colorata in carta dritta 200 mm \u00d8 12 mm da 50"},"content":{"rendered":"<h2>Cannuccia Bubble Tea<\/h2>\n<hr>\n<h3><span style=\"font-weight: bold;\">Scopri la nostra cannuccia Bubble Tea colorata in carta dritta 200 mm \u00d8 12 mm da 50<\/span><\/h3>\n<p><!--more--><\/p>\n<p data-start=\"272\" data-end=\"694\">Gli amanti del <strong>bubble tea<\/strong> lo sanno: impossibile gustare appieno questa bevanda golosa senza una cannuccia adatta. \u00c8 qui che entrano in gioco le nostre <strong data-start=\"411\" data-end=\"457\">cannucce bubble tea dritte in carta colorate \u00d8 12 mm<\/strong>. Progettate appositamente per le <strong data-start=\"504\" data-end=\"525\">perle di tapioca<\/strong> e altri topping generosi, queste cannucce dal <strong data-start=\"570\" data-end=\"588\">diametro largo<\/strong> permettono di aspirare facilmente le perle senza ostruzioni, godendo al contempo di un buon flusso di bevanda.  <\/p>\n<p data-start=\"696\" data-end=\"1104\">Con una <strong data-start=\"702\" data-end=\"724\">lunghezza di 200 mm<\/strong>, sono compatibili con la maggior parte dei <strong>bicchieri utilizzati per bubble tea<\/strong> (<span style=\"color: #d12727;\"><a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/produit\/48-pots-bubbles-tea-en-plastique-95o-rpet-500-ml-thermoscellables\/\">GM500BUBBLE<\/a><\/span>), smoothie, succhi freschi o milkshake. Il loro <strong data-start=\"843\" data-end=\"871\">colore vivace e accattivante<\/strong> aggiunge un tocco di divertimento alle tue bevande, ideale per un servizio professionale o un&#8217;atmosfera conviviale tra amici. Realizzate in <strong data-start=\"1004\" data-end=\"1023\">carta rinforzata<\/strong>, uniscono prestazioni, comfort d&#8217;uso e rispetto dell&#8217;ambiente.  <\/p>\n<p data-start=\"1106\" data-end=\"1391\">Queste <strong>cannucce in carta<\/strong> sono <strong data-start=\"1123\" data-end=\"1155\">monouso ma biodegradabili<\/strong>, perfette per i professionisti della ristorazione impegnati in un approccio pi\u00f9 eco-responsabile. Vendute in <strong data-start=\"1269\" data-end=\"1282\">confezione da 50<\/strong>, sono pronte all&#8217;uso per i tuoi bar <strong>bubble tea<\/strong>, food truck, caff\u00e8 o per i tuoi eventi privati. <\/p>\n<p data-start=\"1393\" data-end=\"1506\">Scegli un accessorio pratico, estetico e sostenibile per accompagnare le tue bevande di tendenza.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h4>I vantaggi:<\/h4>\n<ul>\n<li>Diametro largo (\u00d8 12 mm) perfetto per le perle di tapioca.<\/li>\n<li><strong>Carta rinforzata<\/strong>: solida e biodegradabile.<\/li>\n<li>Lunghezza ideale (200 mm) per bicchieri classici.<\/li>\n<li>Colori vari per un servizio festoso e visivo.<\/li>\n<li>Confezione da 50 cannucce, pronta all&#8217;uso.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h4>Altre informazioni:<\/h4>\n<ul>\n<li><strong>Confezionamento<\/strong>: Pacchetto da 50<\/li>\n<li><b>Altezza:<\/b> 200 mm<\/li>\n<li><strong>Diametro<\/strong>: 12 mm<\/li>\n<li><strong>Materiali<\/strong>: Carta<\/li>\n<li><strong>Colore:<\/strong> Rosa \/ azzurro \/ blu \/ viola \/ giallo<\/li>\n<li><strong>Categoria<\/strong>: Cannuccia bubble tea<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><span style=\"color: #d12727;\"><span style=\"color: #000000;\">Trova qui la nostra cannuccia bubble tea kraft<\/span>: <a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/produit\/50-paille-bubble-tea-droite-210-mm-papier-kraft-o-12-mm\/\">PAILP210X12K<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/gamma-bio\/posate-cannucce\/cannucce-bio\/\">Consulta qui il resto della nostra gamma di cannucce in carta<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cannuccia Bubble Tea Scopri la nostra cannuccia Bubble Tea colorata in carta dritta 200 mm \u00d8 12 mm da 50<\/p>\n","protected":false},"featured_media":271627,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[10346,10375,10878,10924,10350,11437,10923],"product_tag":[],"class_list":{"0":"post-271625","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-imballaggi-alimentari","7":"product_cat-ristorazione","8":"product_cat-piatti-posate-monouso-cannucce","9":"product_cat-cannucce","10":"product_cat-gamma-bio","11":"product_cat-posate-cannucce","12":"product_cat-cannucce-bio","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cannuccia Bubble Tea Colorata in Carta Dritta 200 mm \u00d8 12 mm<\/title>\n<meta name=\"description\" content=\"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cannuccia Bubble Tea Dritta Carta - 200 cm \/ \u00d812 mm\" \/>\n<meta property=\"og:description\" content=\"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/csjemballages\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-29T00:12:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Cannuccia Bubble Tea Dritta Carta - 200 cm \/ \u00d812 mm\" \/>\n<meta name=\"twitter:description\" content=\"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/\",\"name\":\"Cannuccia Bubble Tea Colorata in Carta Dritta 200 mm \u00d8 12 mm\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp\",\"datePublished\":\"2024-11-21T01:18:20+00:00\",\"dateModified\":\"2026-08-29T00:12:44+00:00\",\"description\":\"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp\",\"width\":800,\"height\":800,\"caption\":\"Paille Bubble Tea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cannuccia Bubble Tea colorata in carta dritta 200 mm \u00d8 12 mm da 50\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cannuccia Bubble Tea Colorata in Carta Dritta 200 mm \u00d8 12 mm","description":"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/","og_locale":"it_IT","og_type":"article","og_title":"Cannuccia Bubble Tea Dritta Carta - 200 cm \/ \u00d812 mm","og_description":"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50","og_url":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/","og_site_name":"CSJ Emballages","article_publisher":"https:\/\/www.facebook.com\/csjemballages","article_modified_time":"2026-08-29T00:12:44+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Cannuccia Bubble Tea Dritta Carta - 200 cm \/ \u00d812 mm","twitter_description":"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/","url":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/","name":"Cannuccia Bubble Tea Colorata in Carta Dritta 200 mm \u00d8 12 mm","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp","datePublished":"2024-11-21T01:18:20+00:00","dateModified":"2026-08-29T00:12:44+00:00","description":"Scopri la nostra selezione di cannucce Bubble Tea colorate in carta, robuste, ecologiche e ideali per gustare i tuoi bubble tea. Confezione da 50","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#primaryimage","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C.webp","width":800,"height":800,"caption":"Paille Bubble Tea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/cannuccia-bubble-tea-colorata-in-carta-dritta-200-mm-o-12-mm-da-50\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.csj-emballages.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Cannuccia Bubble Tea colorata in carta dritta 200 mm \u00d8 12 mm da 50"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/it\/#website","url":"https:\/\/www.csj-emballages.com\/it\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/it\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"df_price":1.78,"df_sale_price":"","df_regular_price":1.78,"df_image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/11\/PAILP200X12C-300x300.webp","tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":1,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product\/271625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media\/271627"}],"wp:attachment":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media?parent=271625"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_brand?post=271625"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat?post=271625"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_tag?post=271625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}