{"id":271387,"date":"2025-08-20T08:21:43","date_gmt":"2025-08-20T06:21:43","guid":{"rendered":"https:\/\/www.csj-emballages.com\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/"},"modified":"2026-08-28T02:11:57","modified_gmt":"2026-08-28T00:11:57","slug":"sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20","status":"publish","type":"product","link":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/","title":{"rendered":"Sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20"},"content":{"rendered":"<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<h2><strong style=\"font-family: Roboto, sans-serif;\">Sacchetto gelo  <\/strong><\/h2>\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"text-align: center;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif; text-align: left;\">\n<hr>\n<h3 style=\"text-align: left;\">Descrizione del nostro sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20<\/h3>\n<p><!--more--><\/p>\n<p data-start=\"233\" data-end=\"570\">Pratici, solidi e sicuri, questi <strong data-start=\"265\" data-end=\"320\">sacchetti gelo zip 40 micron 20 x 32 cm (confezione da 20)<\/strong> sono l\u2019accessorio indispensabile per conservare i tuoi alimenti nelle migliori condizioni. Progettati per rispondere alle esigenze di privati e professionisti, uniscono <strong data-start=\"510\" data-end=\"567\">qualit\u00e0, praticit\u00e0 e rispetto delle norme alimentari<\/strong>. <\/p>\n<p data-start=\"572\" data-end=\"1080\">Grazie alla loro <strong data-start=\"585\" data-end=\"610\">chiusura zip ermetica<\/strong>, puoi conservare le tue preparazioni senza rischi di perdite o odori che si diffondono nel congelatore. I <strong>sacchetti<\/strong> <strong>gelo<\/strong> sono realizzati in plastica da <strong data-start=\"762\" data-end=\"788\">40 micron di spessore<\/strong>, il che conferisce loro un&#8217;eccellente resistenza agli strappi e una durata di conservazione prolungata per i tuoi prodotti alimentari. Grazie al formato di <strong>20 x 32 cm,<\/strong> questo <strong>sacchetto gelo<\/strong> \u00e8 ideale per porzioni individuali, frutta tagliata, avanzi o carne e pesce da congelare.  <\/p>\n<p data-start=\"1082\" data-end=\"1444\">Versatili, non si limitano al congelamento: puoi usarli anche a freddo per conservare gli alimenti in frigorifero, trasportare snack o persino riporre piccoli oggetti quotidiani. Completamente <strong data-start=\"1308\" data-end=\"1323\">riciclabili<\/strong>, si inseriscono in un approccio pi\u00f9 responsabile, pur restando perfettamente idonei al <strong data-start=\"1418\" data-end=\"1441\">contatto alimentare<\/strong>. <\/p>\n<p data-start=\"1446\" data-end=\"1708\">Inoltre, ogni sacchetto \u00e8 <strong data-start=\"1464\" data-end=\"1475\">dotato di codice EAN<\/strong>, facilitando la gestione dello stock e il tracciamento per i professionisti. Che tu sia un catering, un ristoratore o un privato attento a organizzare bene le scorte, questi <strong>sacchetti gelo zip<\/strong> sono la soluzione. <\/p>\n<p data-start=\"1710\" data-end=\"1845\">In sintesi, i tuoi prodotti sono protetti, preservati e il tuo congelatore resta perfettamente in ordine.<\/p>\n<p data-start=\"1710\" data-end=\"1845\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<h4 style=\"text-align: left;\"><strong>Vantaggi:<\/strong><\/h4>\n<ul style=\"text-align: left;\">\n<li>Chiusura zip ermetica e pratica.<\/li>\n<li><strong>Resistenza rinforzata<\/strong>: 40 micron di spessore.<\/li>\n<li>Utilizzo a freddo o congelamento.<\/li>\n<li>100% riciclabili e rispettosi dell&#8217;ambiente.<\/li>\n<li>Contatto alimentare garantito.<\/li>\n<li>Articolo con codice EAN per una migliore gestione.<\/li>\n<\/ul>\n<\/div>\n<div style=\"font-family: Roboto, sans-serif;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<h4>Altre informazioni:<\/h4>\n<ul>\n<li><strong>Confezione<\/strong>: Pacco da 20<\/li>\n<li><strong>Dimensioni<\/strong>: 20 x 32 cm<\/li>\n<li><strong>Resistenza<\/strong>: 40 micron<\/li>\n<\/ul>\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>Questo prodotto esiste in diverse misure: <span style=\"color: #d12727;\"><a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetti-freezer-con-zip-40-micron-18-x-22-cm-da-20\/\">18 x 22 cm<\/a><\/span> \/ <span style=\"color: #d12727;\"><a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetti-freezer-con-zip-40-micron-30-x-40-cm-confezione-da-10\/\">30 x 40 cm<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<div style=\"font-family: Roboto, sans-serif;\">\n<p><!--more--><\/p>\n<p><a href=\"\/?product_cat=sacs-sous-vide-lisses-90-\u03bcm\">Consulta il resto della nostra gamma di sacchetti gelo zip<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sacchetto gelo Descrizione del nostro sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20<\/p>\n","protected":false},"featured_media":271390,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[10346,10381,11412,11417],"product_tag":[],"class_list":{"0":"post-271387","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-imballaggi-alimentari","7":"product_cat-macelleria-gastronomia-ortofrutta","8":"product_cat-sacchetti-e-buste","9":"product_cat-sacchetti-freezer","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sacchetto Gelo Zip 40 Micron 20 x 32 cm Confezione da 20<\/title>\n<meta name=\"description\" content=\"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20\" \/>\n<meta property=\"og:description\" content=\"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/csjemballages\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T00:11:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/\",\"name\":\"Sacchetto Gelo Zip 40 Micron 20 x 32 cm Confezione da 20\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp\",\"datePublished\":\"2025-08-20T06:21:43+00:00\",\"dateModified\":\"2026-08-28T00:11:57+00:00\",\"description\":\"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp\",\"width\":800,\"height\":800,\"caption\":\"Sac cong\u00e9lation\u00a0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sacchetto Gelo Zip 40 Micron 20 x 32 cm Confezione da 20","description":"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/","og_locale":"it_IT","og_type":"article","og_title":"Sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20","og_description":"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.","og_url":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/","og_site_name":"CSJ Emballages","article_publisher":"https:\/\/www.facebook.com\/csjemballages","article_modified_time":"2026-08-28T00:11:57+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/","url":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/","name":"Sacchetto Gelo Zip 40 Micron 20 x 32 cm Confezione da 20","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp","datePublished":"2025-08-20T06:21:43+00:00","dateModified":"2026-08-28T00:11:57+00:00","description":"Sacchetti gelo zip 40 micron 20 x 32 cm confezione da 20: resistenti, riciclabili e idonei al contatto alimentare, per una conservazione pratica e sicura.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#primaryimage","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032.webp","width":800,"height":800,"caption":"Sac cong\u00e9lation\u00a0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/sacchetto-gelo-zip-40-micron-20-x-32-cm-confezione-da-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.csj-emballages.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Sacchetto gelo zip 40 micron 20 x 32 cm confezione da 20"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/it\/#website","url":"https:\/\/www.csj-emballages.com\/it\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/it\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"df_price":1.04,"df_sale_price":"","df_regular_price":1.04,"df_image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/08\/CONZ2032-300x300.webp","tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":1,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product\/271387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media\/271390"}],"wp:attachment":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media?parent=271387"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_brand?post=271387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat?post=271387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_tag?post=271387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}