{"id":268034,"date":"2024-03-01T16:53:15","date_gmt":"2024-03-01T15:53:15","guid":{"rendered":"https:\/\/www.csj-emballages.com\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/"},"modified":"2026-08-26T02:13:33","modified_gmt":"2026-08-26T00:13:33","slug":"bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48","status":"publish","type":"product","link":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/","title":{"rendered":"Bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48"},"content":{"rendered":"<h2 class=\"p1\">Bicchiere bubble tea<\/h2>\n<hr>\n<h3>Scopri il nostro bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48<\/h3>\n<p><!--more--><\/p>\n<p data-start=\"272\" data-end=\"615\">Il <strong>bicchiere Bubble Tea plastica \u00d895 RPET 500 ml<\/strong> <strong>termosigillabile<\/strong> \u00e8 appositamente progettato per la vendita da asporto di bubble tea. La sua grande <strong>capacit\u00e0 di 500 ml<\/strong> permette di <strong>offrire porzioni generose<\/strong>, perfettamente adatte alle aspettative dei consumatori. <\/p>\n<p data-start=\"617\" data-end=\"872\">Realizzato in <strong>RPET<\/strong> (plastica riciclata), questo <strong>bicchiere<\/strong> unisce resistenza e approccio pi\u00f9 responsabile. La sua trasparenza ottimale valorizza gli strati della bevanda, le perle di tapioca e il ghiaccio, offrendo un risultato visivo attraente in vetrina come nel servizio. <\/p>\n<p data-start=\"874\" data-end=\"1253\">Grazie al suo <strong>diametro \u00d895 mm,<\/strong> \u00e8 compatibile con le macchine termosigillanti, garantendo una chiusura ermetica e sicura. Questa soluzione \u00e8 ideale per i professionisti che desiderano limitare i rischi di perdite e assicurare un trasporto affidabile delle bevande. Pu\u00f2 anche essere abbinato a un coperchio compatibile (venduto separatamente) secondo la modalit\u00e0 di servizio scelta.  <\/p>\n<p data-start=\"1255\" data-end=\"1528\">Solido e stabile, questo <strong>bicchiere<\/strong> \u00e8 perfetto per <strong>bar di bubble tea, snack, ristoranti, panetterie e negozi specializzati<\/strong>. Confezionato in lotti da <strong>48 unit\u00e0<\/strong>, \u00e8 adatto alle esigenze dei professionisti che cercano prestazioni, praticit\u00e0 e valorizzazione del prodotto. <\/p>\n<p data-start=\"1255\" data-end=\"1528\">\n<p data-start=\"1255\" data-end=\"1528\"><!--more--><\/p>\n<p data-start=\"1255\" data-end=\"1528\"><strong><span style=\"color: #ff0000;\">*BICCHIERI RISERVATI PER ALIMENTI E NON PER BEVANDE<\/span><\/strong><\/p>\n<p data-start=\"1255\" data-end=\"1528\">\n<p data-start=\"1255\" data-end=\"1528\"><!--more--><\/p>\n<h4 data-start=\"1255\" data-end=\"1528\">Vantaggi:<\/h4>\n<ul>\n<li data-start=\"1566\" data-end=\"1615\">Grande capacit\u00e0 <strong>500 ml<\/strong> ideale per bubble tea.<\/li>\n<li data-start=\"1618\" data-end=\"1642\">Plastica <strong>RPET riciclata<\/strong>.<\/li>\n<li data-start=\"1645\" data-end=\"1684\">Trasparente per valorizzare la bevanda.<\/li>\n<li data-start=\"1687\" data-end=\"1734\"><strong>Termosigillabile<\/strong> per una chiusura ermetica.<\/li>\n<li data-start=\"1737\" data-end=\"1756\">Compatibile <strong>\u00d895 mm<\/strong>.<\/li>\n<li data-start=\"1759\" data-end=\"1790\">Buona resistenza e stabilit\u00e0.<\/li>\n<li data-start=\"1793\" data-end=\"1823\">Adatto alla vendita da asporto.<\/li>\n<li data-start=\"1826\" data-end=\"1864\">Confezionamento pratico da <strong>48 bicchieri<\/strong>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h4>Altre informazioni:<\/h4>\n<ul>\n<li><strong>Confezionamento<\/strong>: Confezione da 48<\/li>\n<li><strong>Dimensioni<\/strong>: 95 mm x 114 mm ( \u00d8 x H )<\/li>\n<li><strong>Volume<\/strong>: 500 ml<\/li>\n<li><strong>Materiale<\/strong>: RPET<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/imballaggi-alimentari\/ristorazione\/bicchieri-calici-bottiglie\/bicchieri-plastica\/bicchieri-bubble-tea-termosigillabili\/\">Consulta il resto della nostra gamma di bicchieri bubble tea termosigillabili<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bicchiere bubble tea Scopri il nostro bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48<\/p>\n","protected":false},"featured_media":268037,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[10346,10375,10409,10419,10672,10358],"product_tag":[],"class_list":{"0":"post-268034","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-imballaggi-alimentari","7":"product_cat-ristorazione","8":"product_cat-bicchieri-calici-bottiglie","9":"product_cat-bicchieri-plastica","10":"product_cat-bicchieri-bubble-tea-termosigillabili","11":"product_cat-stock","13":"first","14":"instock","15":"sale","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bicchiere Bubble Tea in Plastica RPET 500 ml Termosigillabile confezione da 48<\/title>\n<meta name=\"description\" content=\"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48\" \/>\n<meta property=\"og:description\" content=\"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/csjemballages\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T00:13:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/\",\"name\":\"Bicchiere Bubble Tea in Plastica RPET 500 ml Termosigillabile confezione da 48\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp\",\"datePublished\":\"2024-03-01T15:53:15+00:00\",\"dateModified\":\"2026-08-26T00:13:33+00:00\",\"description\":\"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp\",\"width\":800,\"height\":800,\"caption\":\"Pot bubbles tea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bicchiere Bubble Tea in Plastica RPET 500 ml Termosigillabile confezione da 48","description":"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/","og_locale":"it_IT","og_type":"article","og_title":"Bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48","og_description":"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.","og_url":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/","og_site_name":"CSJ Emballages","article_publisher":"https:\/\/www.facebook.com\/csjemballages","article_modified_time":"2026-08-26T00:13:33+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/","url":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/","name":"Bicchiere Bubble Tea in Plastica RPET 500 ml Termosigillabile confezione da 48","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp","datePublished":"2024-03-01T15:53:15+00:00","dateModified":"2026-08-26T00:13:33+00:00","description":"Bicchiere Bubble Tea \u00d895 mm RPET 500 ml termosigillabile venduto in confezione da 48. Trasparente e resistente, ideale per bubble tea da asporto.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#primaryimage","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE.webp","width":800,"height":800,"caption":"Pot bubbles tea"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/it\/produit\/bicchiere-bubble-tea-in-plastica-95o-rpet-500-ml-termosigillabile-confezione-da-48\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/www.csj-emballages.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Bicchiere bubble tea in plastica 95\u00d8 RPET 500 ml termosigillabile confezione da 48"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/it\/#website","url":"https:\/\/www.csj-emballages.com\/it\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/it\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"df_price":4.93,"df_sale_price":4.93,"df_regular_price":5.72,"df_image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/GM500BUBBLE-300x300.webp","tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":1,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product\/268034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media\/268037"}],"wp:attachment":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media?parent=268034"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_brand?post=268034"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_cat?post=268034"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/product_tag?post=268034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}