{"id":266696,"date":"2024-04-12T15:46:14","date_gmt":"2024-04-12T13:46:14","guid":{"rendered":"https:\/\/www.csj-emballages.com\/mondo-alimentare\/"},"modified":"2026-04-27T07:46:03","modified_gmt":"2026-04-27T05:46:03","slug":"mondo-alimentare","status":"publish","type":"page","link":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/","title":{"rendered":"Mondo alimentare"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"266696\" class=\"elementor elementor-266696 elementor-4930\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b23208 e-con-full e-flex e-con e-parent\" data-id=\"9b23208\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f58a2d elementor-widget elementor-widget-image\" data-id=\"9f58a2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1431\" height=\"259\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation.webp\" class=\"attachment-full size-full wp-image-278597\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation.webp 1431w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation-300x54.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation-1024x185.webp 1024w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation-768x139.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/04\/Alimentation-600x109.webp 600w\" sizes=\"(max-width: 1431px) 100vw, 1431px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fc40e5 e-flex e-con-boxed e-con e-parent\" data-id=\"2fc40e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14a4777 elementor-widget elementor-widget-heading\" data-id=\"14a4777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CSJ alimentari<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e430ea elementor-widget elementor-widget-text-editor\" data-id=\"6e430ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>CSJ alimentari<\/b> mette l\u2019accento sulla qualit\u00e0 degli ingredienti di base per piatti indimenticabili. La nostra gamma comprende <a href=\"\/?product_cat=bases-fonds-culinaires\">basi culinarie<\/a>, <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/spezie-semplici\/\">spezie semplici<\/a> e <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/spezie-composte\/\">composte<\/a>, <a href=\"\/?product_cat=aliments\">conserve<\/a>, <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/budella\/\">budelli<\/a> e <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/marinature\/\">marinate<\/a>, selezionate appositamente per stimolare la tua creativit\u00e0 in cucina. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec6c0b9 e-flex e-con-boxed e-con e-parent\" data-id=\"ec6c0b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7f72a e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"ba7f72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_justify_horizontal&quot;:&quot;stretch&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"195557162\" aria-label=\"Schede. Apri gli elementi con Invio o Spazio, chiudili con Esc e naviga con i tasti freccia.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-1955571621\" data-tab-title-id=\"e-n-tab-title-1955571621\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-1955571621\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tLe nostre promozioni\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1955571622\" data-tab-title-id=\"e-n-tab-title-1955571622\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1955571622\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tLa nostra selezione\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-1955571623\" data-tab-title-id=\"e-n-tab-title-1955571623\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-1955571623\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tLe nostre novit\u00e0\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-1955571621\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1955571621\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-2e879ef e-con-full e-flex e-con e-child\" data-id=\"2e879ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e2d8d6e e-flex e-con-boxed e-con e-child\" data-id=\"e2d8d6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fec60a6 elementor-grid-5 nt-home-promotions elementor-grid-tablet_extra-3 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"fec60a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-5 \"><ul class=\"products elementor-grid columns-5\">\n<li class=\"product type-product post-268646 status-publish first instock product_cat-alimentari product_cat-anti-spreco product_cat-imballaggi-alimentari product_cat-svuota-magazzino product_cat-marinature has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='268646' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/marinata-indiana-5-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-30%<\/span>\r\n<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Marinade indienne\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-indienne.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 10655<\/p><h2 class=\"woocommerce-loop-product__title\">Marinata indiana 5 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>54,55&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 54,55&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>38,19&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 38,19&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=268646\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_268646\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"268646\" data-product_sku=\"10655\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Marinata indiana 5 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Marinata indiana 5 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_268646\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"268646\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;268646&quot;,&quot;item_id&quot;:&quot;268646&quot;,&quot;item_name&quot;:&quot;Marinata indiana 5 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:38.19,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:1}\"><\/span><\/li>\n<li class=\"product type-product post-267225 status-publish instock product_cat-alimentari product_cat-anti-spreco product_cat-imballaggi-alimentari product_cat-spezie product_cat-spezie-semplici has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='267225' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/finocchio-macinato-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-30%<\/span>\r\n<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Fenouil moulu\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fenouil-moulu.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 10400<\/p><h2 class=\"woocommerce-loop-product__title\">Finocchio macinato 1 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>12,60&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 12,60&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>8,82&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 8,82&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=267225\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_267225\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"267225\" data-product_sku=\"10400\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Finocchio macinato 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Finocchio macinato 1 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_267225\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"267225\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;267225&quot;,&quot;item_id&quot;:&quot;267225&quot;,&quot;item_name&quot;:&quot;Finocchio macinato 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:8.82,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:2}\"><\/span><\/li>\n<li class=\"product type-product post-270797 status-publish instock product_cat-alimentari product_cat-anti-spreco product_cat-frutta-secca product_cat-imballaggi-alimentari has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270797' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/farina-di-mandorle-grezza-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-30%<\/span>\r\n<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Poudre d&#039;amande\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/poudre-amande-brute-1.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 440018<\/p><h2 class=\"woocommerce-loop-product__title\">Farina di mandorle grezza 1 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>13,26&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 13,26&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>9,28&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 9,28&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270797\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270797\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270797\" data-product_sku=\"440018\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Farina di mandorle grezza 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Farina di mandorle grezza 1 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270797\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270797\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270797&quot;,&quot;item_id&quot;:&quot;270797&quot;,&quot;item_name&quot;:&quot;Farina di mandorle grezza 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:9.28,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:3}\"><\/span><\/li>\n<li class=\"product type-product post-267258 status-publish instock product_cat-alimentari product_cat-svuota-magazzino product_cat-spezie product_cat-spezie-semplici has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='267258' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/basilico-macinato-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-20%<\/span>\r\n<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Basilic moulu\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Basilic-moulu.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 10295<\/p><h2 class=\"woocommerce-loop-product__title\">Basilico macinato 1 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>8,97&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 8,97&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7,17&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 7,17&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=267258\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_267258\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"267258\" data-product_sku=\"10295\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Basilico macinato 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Basilico macinato 1 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_267258\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"267258\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;267258&quot;,&quot;item_id&quot;:&quot;267258&quot;,&quot;item_name&quot;:&quot;Basilico macinato 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:7.17,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Spezie&quot;,&quot;item_category3&quot;:&quot;Spezie semplici&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:4}\"><\/span><\/li>\n<li class=\"product type-product post-270408 status-publish last instock product_cat-alimentari product_cat-anti-spreco product_cat-frutta-secca product_cat-imballaggi-alimentari has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270408' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/farina-di-nocciole-grezza-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-30%<\/span>\r\n<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Poudre de noisette\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/noisette-poudre-brute.webp 801w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 480002<\/p><h2 class=\"woocommerce-loop-product__title\">Farina di nocciole grezza 1 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>22,88&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 22,88&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>16,02&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 16,02&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270408\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270408\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270408\" data-product_sku=\"480002\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Farina di nocciole grezza 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Farina di nocciole grezza 1 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270408\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270408\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270408&quot;,&quot;item_id&quot;:&quot;270408&quot;,&quot;item_name&quot;:&quot;Farina di nocciole grezza 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:16.02,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:5}\"><\/span><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1955571622\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1955571622\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-868ce93 e-con-full e-flex e-con e-child\" data-id=\"868ce93\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2bda08a e-flex e-con-boxed e-con e-child\" data-id=\"2bda08a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f45216b elementor-grid-5 nt-home-selection elementor-grid-tablet_extra-3 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"f45216b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-5 \"><ul class=\"products elementor-grid columns-5\">\n<li class=\"product type-product post-271188 status-publish first instock product_cat-alimentari product_cat-frutta-secca has-post-thumbnail featured taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='271188' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/prugne-secche-denocciolate-da-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pruneaux s\u00e9ch\u00e9s\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/Pruneaux-seches.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 160011<\/p><h2 class=\"woocommerce-loop-product__title\">Prugne secche denocciolate da 1 kg<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>9,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=271188\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_271188\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"271188\" data-product_sku=\"160011\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Prugne secche denocciolate da 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Prugne secche denocciolate da 1 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_271188\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"271188\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;271188&quot;,&quot;item_id&quot;:&quot;271188&quot;,&quot;item_name&quot;:&quot;Prugne secche denocciolate da 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:9.95,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Spezie&quot;,&quot;item_category3&quot;:&quot;Spezie semplici&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:1}\"><\/span><\/li>\n<li class=\"product type-product post-270839 status-publish instock product_cat-alimentari product_cat-conserve product_cat-frutta-sciroppata-2 product_cat-quetsche has-post-thumbnail featured taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270839' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/prugne-quetsche-denocciolate-in-scatola-2-1\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Quetsches d\u00e9noyaut\u00e9es\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/070017.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 070017<\/p><h2 class=\"woocommerce-loop-product__title\">Prugne quetsche denocciolate in scatola 2\/1<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>7,57&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270839\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270839\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270839\" data-product_sku=\"070017\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Prugne quetsche denocciolate in scatola 2\/1&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Prugne quetsche denocciolate in scatola 2\/1&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270839\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270839\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270839&quot;,&quot;item_id&quot;:&quot;270839&quot;,&quot;item_name&quot;:&quot;Prugne quetsche denocciolate in scatola 2\\\/1&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:7.57,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Conserve&quot;,&quot;item_category3&quot;:&quot;Frutta sciroppata&quot;,&quot;item_category4&quot;:&quot;Susine&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:2}\"><\/span><\/li>\n<li class=\"product type-product post-270926 status-publish onbackorder product_cat-albicocche product_cat-alimentari product_cat-anti-spreco product_cat-conserve product_cat-frutta-sciroppata-2 product_cat-imballaggi-alimentari has-post-thumbnail sale featured taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270926' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/albicocche-a-meta-non-pelate-in-latta-4-4\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-35%<\/span>\r\n<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Oreillons d&#039;abricots\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010124.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 010124<\/p><h2 class=\"woocommerce-loop-product__title\">Albicocche a met\u00e0 non pelate in latta 4\/4<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>3,01&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 3,01&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>1,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 1,95&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270926\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270926\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270926\" data-product_sku=\"010124\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Albicocche a met\u00e0 non pelate in latta 4\/4&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Albicocche a met\u00e0 non pelate in latta 4\/4&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270926\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270926\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270926&quot;,&quot;item_id&quot;:&quot;270926&quot;,&quot;item_name&quot;:&quot;Albicocche a met\\u00e0 non pelate in latta 4\\\/4&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:1.95,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:3}\"><\/span><\/li>\n<li class=\"product type-product post-270945 status-publish instock product_cat-albicocche product_cat-alimentari product_cat-conserve product_cat-frutta-sciroppata-2 has-post-thumbnail featured taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270945' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/mezze-albicocche-qualita-pasticceria-non-pelate-in-scatola-3-1\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Oreillons d&#039;abricots\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/010125.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 010125<\/p><h2 class=\"woocommerce-loop-product__title\">Mezze albicocche qualit\u00e0 pasticceria non pelate in scatola 3\/1<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>10,72&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270945\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270945\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270945\" data-product_sku=\"010125\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Mezze albicocche qualit\u00e0 pasticceria non pelate in scatola 3\/1&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Mezze albicocche qualit\u00e0 pasticceria non pelate in scatola 3\/1&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270945\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270945\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270945&quot;,&quot;item_id&quot;:&quot;270945&quot;,&quot;item_name&quot;:&quot;Mezze albicocche qualit\\u00e0 pasticceria non pelate in scatola 3\\\/1&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:10.72,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Conserve&quot;,&quot;item_category3&quot;:&quot;Frutta sciroppata&quot;,&quot;item_category4&quot;:&quot;Albicocche&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:4}\"><\/span><\/li>\n<li class=\"product type-product post-273796 status-publish last outofstock product_cat-alimentari product_cat-caffe-in-grani has-post-thumbnail featured taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='273796' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/caffe-in-grani-las-vegas-70-arabica-30-robusta-da-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Caf\u00e9 en grains\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/13001.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 13001<\/p><h2 class=\"woocommerce-loop-product__title\">Caff\u00e8 in grani Las Vegas 70% arabica \/ 30% robusta da 1 kg<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>14,32&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/caffe-in-grani-las-vegas-70-arabica-30-robusta-da-1-kg\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_273796\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"273796\" data-product_sku=\"13001\" aria-label=\"En savoir plus sur &ldquo;Caff\u00e8 in grani Las Vegas 70% arabica \/ 30% robusta da 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Lire la suite<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_273796\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"273796\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;273796&quot;,&quot;item_id&quot;:&quot;273796&quot;,&quot;item_name&quot;:&quot;Caff\\u00e8 in grani Las Vegas 70% arabica \\\/ 30% robusta da 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:14.32,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Conserve&quot;,&quot;item_category3&quot;:&quot;Frutta sciroppata&quot;,&quot;item_category4&quot;:&quot;Albicocche&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:5}\"><\/span><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-1955571623\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-1955571623\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-fb143e4 e-con-full e-flex e-con e-child\" data-id=\"fb143e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9686df3 e-flex e-con-boxed e-con e-child\" data-id=\"9686df3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c691084 elementor-grid-5 nt-home-selection elementor-grid-tablet_extra-3 elementor-grid-tablet-3 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"c691084\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-5 \"><ul class=\"products elementor-grid columns-5\">\n<li class=\"product type-product post-270828 status-publish first instock product_cat-alimentari product_cat-conserve product_cat-frutta-sciroppata-2 product_cat-pesche has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='270828' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/mezze-pesche-sciroppate-in-lattina-3-1\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Oreillons de p\u00eaches\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/040056.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 040056<\/p><h2 class=\"woocommerce-loop-product__title\">Mezze pesche sciroppate in lattina 3\/1<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>8,18&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=270828\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_270828\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"270828\" data-product_sku=\"040056\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Mezze pesche sciroppate in lattina 3\/1&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Mezze pesche sciroppate in lattina 3\/1&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_270828\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"270828\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;270828&quot;,&quot;item_id&quot;:&quot;270828&quot;,&quot;item_name&quot;:&quot;Mezze pesche sciroppate in lattina 3\\\/1&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:8.18,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Conserve&quot;,&quot;item_category3&quot;:&quot;Frutta sciroppata&quot;,&quot;item_category4&quot;:&quot;Pesche&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:1}\"><\/span><\/li>\n<li class=\"product type-product post-271483 status-publish instock product_cat-alimentari product_cat-aromi product_cat-pasticceria has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='271483' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/aroma-liquido-rosa-500-ml\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ar\u00f4me liquide rose\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/12\/Arome-rose.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 12013<\/p><h2 class=\"woocommerce-loop-product__title\">Aroma liquido rosa 500 ml<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>3,95&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=271483\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_271483\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"271483\" data-product_sku=\"12013\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Aroma liquido rosa 500 ml&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Aroma liquido rosa 500 ml&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_271483\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"271483\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;271483&quot;,&quot;item_id&quot;:&quot;271483&quot;,&quot;item_name&quot;:&quot;Aroma liquido rosa 500 ml&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:3.95,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Conserve&quot;,&quot;item_category3&quot;:&quot;Frutta sciroppata&quot;,&quot;item_category4&quot;:&quot;Pesche&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:2}\"><\/span><\/li>\n<li class=\"product type-product post-271199 status-publish instock product_cat-alimentari product_cat-ananas product_cat-conserve product_cat-frutta-sciroppata-2 product_cat-imballaggi-alimentari has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='271199' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/ananas-a-fette-intere-in-scatola-3-4\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Ananas en tranches\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-768x768.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-600x600.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/04\/100095-2.webp 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 100095<\/p><h2 class=\"woocommerce-loop-product__title\">Ananas a fette intere in scatola 3\/4<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>3,04&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=271199\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_271199\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"271199\" data-product_sku=\"100095\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Ananas a fette intere in scatola 3\/4&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Ananas a fette intere in scatola 3\/4&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_271199\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"271199\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;271199&quot;,&quot;item_id&quot;:&quot;271199&quot;,&quot;item_name&quot;:&quot;Ananas a fette intere in scatola 3\\\/4&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:3.04,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:3}\"><\/span><\/li>\n<li class=\"product type-product post-267249 status-publish outofstock product_cat-alimentari product_cat-spezie product_cat-spezie-semplici has-post-thumbnail taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='267249' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/semi-di-coriandolo-1-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-300x300.webp\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Grains de coriandre 1kg\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-300x300.webp 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-150x150.webp 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-768x769.webp 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-600x601.webp 600w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre-100x100.webp 100w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Grains-de-coriandre.webp 799w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 10380<\/p><h2 class=\"woocommerce-loop-product__title\">Semi di coriandolo 1 kg<\/h2>\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>6,72&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/semi-di-coriandolo-1-kg\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_267249\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"267249\" data-product_sku=\"10380\" aria-label=\"En savoir plus sur &ldquo;Semi di coriandolo 1 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Lire la suite<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_267249\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"267249\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;267249&quot;,&quot;item_id&quot;:&quot;267249&quot;,&quot;item_name&quot;:&quot;Semi di coriandolo 1 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:6.72,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Alimentari&quot;,&quot;item_category2&quot;:&quot;Spezie&quot;,&quot;item_category3&quot;:&quot;Spezie semplici&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:4}\"><\/span><\/li>\n<li class=\"product type-product post-267202 status-publish last instock product_cat-alimentari product_cat-anti-spreco product_cat-imballaggi-alimentari product_cat-svuota-magazzino product_cat-merguez-salsicce-chorizo product_cat-spezie-composte product_cat-spezie has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<div class='nt-loop-wishlist-button-wrapper nt-wishlist-button-wrapper add' data-product-id='267202' data-add-text='Aggiungi alla mia lista'><button class='nt-wishlist-button' title='Aggiungi alla mia lista'><div class='nt-wishlist-button__tooltip'>Aggiungi alla mia lista<\/div><\/button><\/div><a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/spezie-salsiccia-al-blu-5-kg\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <span class=\"onsale\">-30%<\/span>\r\n<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-04-03-a-11.37.26.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Spezie Salsiccia al Blu 5 kg\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-04-03-a-11.37.26.png 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-04-03-a-11.37.26-150x150.png 150w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-04-03-a-11.37.26-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p class=\"nt-loop-product-sku\">R\u00e9f : 10472<\/p><h2 class=\"woocommerce-loop-product__title\">Spezie Salsiccia al Blu 5 kg<\/h2>\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>52,55&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">Le prix initial \u00e9tait\u00a0: 52,55&nbsp;&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>36,79&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">Le prix actuel est\u00a0: 36,79&nbsp;&euro;.<\/span> <small class=\"woocommerce-price-suffix\">TTC<\/small><\/span>\n<\/a><a href=\"\/it\/wp-json\/wp\/v2\/pages\/266696?add-to-cart=267202\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_267202\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"267202\" data-product_sku=\"10472\" aria-label=\"Ajouter au panier\u00a0: &ldquo;Spezie Salsiccia al Blu 5 kg&rdquo;\" rel=\"nofollow\" data-success_message=\"&quot;Spezie Salsiccia al Blu 5 kg&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Ajouter au panier<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_267202\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<span class=\"gtmkit_product_data\" style=\"display:none;visibility:hidden\" data-gtmkit_product_id=\"267202\" data-gtmkit_product_data=\"{&quot;id&quot;:&quot;267202&quot;,&quot;item_id&quot;:&quot;267202&quot;,&quot;item_name&quot;:&quot;Spezie Salsiccia al Blu 5 kg&quot;,&quot;currency&quot;:&quot;EUR&quot;,&quot;price&quot;:36.79,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Imballaggi alimentari&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:5}\"><\/span><\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19f182a e-flex e-con-boxed e-con e-parent\" data-id=\"19f182a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c471d1 e-flex e-con-boxed e-con e-child\" data-id=\"3c471d1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16f9a75 e-con-full e-flex e-con e-child\" data-id=\"16f9a75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e6fc999 elementor-widget elementor-widget-heading\" data-id=\"e6fc999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I nostri reparti<br>in 1 clic<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe39401 e-con-full e-flex e-con e-child\" data-id=\"fe39401\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0de7bd elementor-widget elementor-widget-text-editor\" data-id=\"f0de7bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CSJ alimentari ti propone un\u2019ampia gamma di prodotti alimentari, principalmente destinati ai professionisti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcbf3be elementor-widget elementor-widget-nt_categories_carousel\" data-id=\"fcbf3be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"nt_categories_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"nt-categories-carousel\">\r\n    <div class=\"nt-categories-carousel__carousel owl-carousel\">\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Fonds-brun.webp); order: 450\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/basi-fondi-culinari\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Basi \/ fondi culinari<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Epices-saucisse-piment-dEspelette.webp); order: 446\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/budella\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Budelli<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/Cafes-en-grains.webp); order: 426\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/caffe-in-grani\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Caff\u00e8 in grani<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/09\/Champignons-secs.webp); order: 427\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/funghi-secchi\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Funghi secchi<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/Conserverie.webp); order: 432\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/conserve\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Conserve<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/05\/Pink-Shakes-or-Food-Advert-Instagram-Post-1.webp); order: 445\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/frutta-secca\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Frutta secca<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Marinade-trois-poivres-1.webp); order: 459\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/marinature\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Marinature<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2026\/03\/Patisserie.webp); order: 428\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/pasticceria\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Pasticceria<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n                                <div class=\"nt-categories-carousel__item-wrapper\" style=\"--nt-item-image: url(https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/05\/Pink-Shakes-or-Food-Advert-Instagram-Post.webp); order: 451\">\r\n                <div class=\"nt-categories-carousel__item-border\">\r\n                    <div class=\"nt-categories-carousel__item-border-inner\">\r\n                        <a class=\"nt-categories-carousel__item-inner\" href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/\">\r\n                            <h3 class=\"nt-categories-carousel__item-title\">Spezie<\/h3>\r\n                            <p class=\"nt-categories-carousel__item-link\">\r\n                                Vedi altro                                <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                            <\/p>\r\n                        <\/a>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79e0592 e-flex e-con-boxed e-con e-parent\" data-id=\"79e0592\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-894b546 e-flex e-con-boxed e-con e-child\" data-id=\"894b546\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5559c14 e-con-full e-flex e-con e-child\" data-id=\"5559c14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf05e62 elementor-widget elementor-widget-heading\" data-id=\"cf05e62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le nostre garanzie<br>e servizi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7199a3d e-con-full e-flex e-con e-child\" data-id=\"7199a3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f124529 elementor-widget elementor-widget-text-editor\" data-id=\"f124529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da CSJ Emballages, la tua soddisfazione \u00e8 fondamentale. Ti garantiamo una consegna rapida e sicura grazie alla nostra rete logistica affidabile. Per i pagamenti, assicuriamo la sicurezza delle tue informazioni con sistemi conformi alle normative.  <span style=\"font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); color: #26385a; font-family: Times; font-size: 12px;\"> <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcaaf07 e-flex e-con-boxed e-con e-child\" data-id=\"bcaaf07\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c3f10a e-con-full e-flex e-con e-child\" data-id=\"1c3f10a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cda2e2d elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cda2e2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"outline\" height=\"512\" viewBox=\"0 0 48 48\" width=\"512\"><path d=\"m41.211 37.288a4.112 4.112 0 1 1 4.109-4.112 4.114 4.114 0 0 1 -4.109 4.112zm0-6.724a2.612 2.612 0 1 0 2.609 2.612 2.613 2.613 0 0 0 -2.609-2.612z\"><\/path><path d=\"m19.542 37.288a4.112 4.112 0 1 1 4.108-4.112 4.115 4.115 0 0 1 -4.108 4.112zm0-6.724a2.612 2.612 0 1 0 2.608 2.612 2.614 2.614 0 0 0 -2.608-2.612z\"><\/path><path d=\"m46.621 33.926h-2.051a.75.75 0 0 1 0-1.5h1.839v-3.977a3.16 3.16 0 0 0 -.4-1.536l-4.06-7.279a.4.4 0 0 0 -.349-.205h-5.533v13h1.786a.75.75 0 0 1 0 1.5h-2.536a.75.75 0 0 1 -.75-.75v-14.5a.75.75 0 0 1 .75-.75h6.283a1.9 1.9 0 0 1 1.66.974l4.059 7.28a4.662 4.662 0 0 1 .589 2.266v4.19a1.289 1.289 0 0 1 -1.287 1.287z\"><\/path><path d=\"m16.183 33.926h-7.191a.75.75 0 0 1 -.75-.75v-5.768a.75.75 0 0 1 1.5 0v5.018h6.441a.75.75 0 0 1 0 1.5z\"><\/path><path d=\"m8.992 24.747a.75.75 0 0 1 -.75-.75v-5.036a.75.75 0 0 1 1.5 0v5.039a.75.75 0 0 1 -.75.747z\"><\/path><path d=\"m35.317 33.926h-12.417a.75.75 0 0 1 0-1.5h11.667v-19.621h-24.825v3.089a.75.75 0 0 1 -1.5 0v-3.227a1.364 1.364 0 0 1 1.363-1.362h25.1a1.364 1.364 0 0 1 1.362 1.362v20.509a.75.75 0 0 1 -.75.75z\"><\/path><path d=\"m11.957 28.158h-9.519a.75.75 0 0 1 0-1.5h9.519a.75.75 0 0 1 0 1.5z\"><\/path><path d=\"m19.542 24.747h-13.283a.75.75 0 0 1 0-1.5h13.283a.75.75 0 0 1 0 1.5z\"><\/path><path d=\"m5.846 20.787h-5.187a.75.75 0 1 1 0-1.5h5.187a.75.75 0 0 1 0 1.5z\"><\/path><path d=\"m14.163 16.644h-9.156a.75.75 0 1 1 0-1.5h9.156a.75.75 0 0 1 0 1.5z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b31211 elementor-widget elementor-widget-heading\" data-id=\"5b31211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Consegna gratuita a partire \nda 299,00 \u20ac + IVA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26a1616 e-con-full e-flex e-con e-child\" data-id=\"26a1616\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9462add elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"9462add\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/Group.svg\" class=\"attachment-large size-large wp-image-267085\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359a470 elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"359a470\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"512\" viewBox=\"0 0 28 28\" width=\"512\"><g id=\"Layer_2\" data-name=\"Layer 2\"><path d=\"m26.186 5.536-5-2a.5.5 0 0 0 -.372 0l-5 2a.5.5 0 0 0 -.314.464v5.168a5.529 5.529 0 0 0 2.671 4.718l2.572 1.543a.5.5 0 0 0 .514 0l2.243-1.346v5.6a.821.821 0 0 1 -.82.82h-19.36a.821.821 0 0 1 -.82-.82v-11.183h11.5a.5.5 0 0 0 0-1h-11.5v-1.18a.821.821 0 0 1 .82-.82h10.68a.5.5 0 0 0 0-1h-10.68a1.821 1.821 0 0 0 -1.82 1.82v13.36a1.821 1.821 0 0 0 1.82 1.82h19.36a1.821 1.821 0 0 0 1.82-1.82v-6.28a5.529 5.529 0 0 0 2-4.234v-5.166a.5.5 0 0 0 -.314-.464zm-.686 5.632a4.522 4.522 0 0 1 -2.186 3.86l-2.314 1.389-2.314-1.389a4.522 4.522 0 0 1 -2.186-3.86v-4.83l4.5-1.8 4.5 1.8z\"><\/path><path d=\"m19.354 9.732a.5.5 0 0 0 -.708.707l1.334 1.333a.5.5 0 0 0 .707 0l2.667-2.667a.5.5 0 0 0 -.708-.707l-2.313 2.314z\"><\/path><path d=\"m5 19.5a.5.5 0 0 0 0 1h4a.5.5 0 0 0 0-1z\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c2384 elementor-widget elementor-widget-heading\" data-id=\"85c2384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pagamenti sicuri con carta, assegno, bonifico, mandati amministrativi...<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab40623 e-con-full e-flex e-con e-child\" data-id=\"ab40623\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd9d832 elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bd9d832\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 512 512\" style=\"enable-background:new 0 0 512 512;\" xml:space=\"preserve\"><g>\t<g>\t\t<g>\t\t\t<path d=\"M458.406,380.681c-8.863-6.593-21.391-4.752-27.984,4.109c-3.626,4.874-7.506,9.655-11.533,14.21    c-7.315,8.275-6.538,20.915,1.737,28.231c3.806,3.364,8.531,5.016,13.239,5.016c5.532,0,11.04-2.283,14.992-6.754    c4.769-5.394,9.364-11.056,13.658-16.829C469.108,399.803,467.269,387.273,458.406,380.681z\"><\/path>\t\t\t<path d=\"M491.854,286.886c-10.786-2.349-21.447,4.496-23.796,15.288c-1.293,5.937-2.855,11.885-4.646,17.681    c-3.261,10.554,2.651,21.752,13.204,25.013c1.967,0.607,3.955,0.896,5.911,0.896c8.54,0,16.448-5.514,19.102-14.102    c2.126-6.878,3.98-13.937,5.514-20.98C509.492,299.89,502.647,289.236,491.854,286.886z\"><\/path>\t\t\t<path d=\"M362.139,444.734c-5.31,2.964-10.808,5.734-16.34,8.233c-10.067,4.546-14.542,16.392-9.996,26.459    c3.34,7.396,10.619,11.773,18.239,11.773c2.752,0,5.549-0.571,8.22-1.777c6.563-2.964,13.081-6.249,19.377-9.764    c9.645-5.384,13.098-17.568,7.712-27.212C383.968,442.803,371.784,439.35,362.139,444.734z\"><\/path>\t\t\t<path d=\"M236,96v151.716l-73.339,73.338c-7.81,7.811-7.81,20.474,0,28.284c3.906,3.906,9.023,5.858,14.143,5.858    c5.118,0,10.237-1.953,14.143-5.858l79.196-79.196c3.75-3.75,5.857-8.838,5.857-14.142V96c0-11.046-8.954-20-20-20    C244.954,76,236,84.954,236,96z\"><\/path>\t\t\t<path d=\"M492,43c-11.046,0-20,8.954-20,20v55.536C425.448,45.528,344.151,0,256,0C187.62,0,123.333,26.629,74.98,74.98    C26.629,123.333,0,187.62,0,256s26.629,132.667,74.98,181.02C123.333,485.371,187.62,512,256,512c0.169,0,0.332-0.021,0.5-0.025    c0.168,0.004,0.331,0.025,0.5,0.025c7.208,0,14.487-0.304,21.637-0.902c11.007-0.922,19.183-10.592,18.262-21.599    c-0.923-11.007-10.58-19.187-21.6-18.261C269.255,471.743,263.099,472,257,472c-0.169,0-0.332,0.021-0.5,0.025    c-0.168-0.004-0.331-0.025-0.5-0.025c-119.103,0-216-96.897-216-216S136.897,40,256,40c76.758,0,147.357,40.913,185.936,106    h-54.993c-11.046,0-20,8.954-20,20s8.954,20,20,20H448c12.18,0,23.575-3.423,33.277-9.353c0.624-0.356,1.224-0.739,1.796-1.152    C500.479,164.044,512,144.347,512,122V63C512,51.954,503.046,43,492,43z\"><\/path>\t\t<\/g>\t<\/g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98d7851 elementor-widget__width-initial elementor-absolute elementor-widget elementor-widget-image\" data-id=\"98d7851\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"48\" height=\"48\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/Group.svg\" class=\"attachment-large size-large wp-image-267085\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b59c6b2 elementor-widget elementor-widget-heading\" data-id=\"b59c6b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Consegna rapida in 48-72 ore<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7287107 e-flex e-con-boxed e-con e-parent\" data-id=\"7287107\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7f2c6f9 e-flex e-con-boxed e-con e-child\" data-id=\"7f2c6f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef0175c e-con-full e-flex e-con e-child\" data-id=\"ef0175c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0b7788 elementor-widget elementor-widget-heading\" data-id=\"d0b7788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le nostre novit\u00e0<br>e consigli<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8226f17 e-con-full e-flex e-con e-child\" data-id=\"8226f17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d16dd30 elementor-widget elementor-widget-text-editor\" data-id=\"d16dd30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #54595f;\">Da CSJ Emballages, ti teniamo aggiornato sulle ultime tendenze e ti diamo consigli pratici per ottimizzare i tuoi acquisti.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17abda8 e-flex e-con-boxed e-con e-child\" data-id=\"17abda8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6bb5d8 elementor-widget elementor-widget-nt_listing_actus\" data-id=\"b6bb5d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"nt_listing_actus.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"nt-listing-actus\">\r\n                    <div class=\"nt-listing-actus__item\">\r\n                <div class=\"nt-listing-actus__item-thumbnail\">\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boulangerie-jpg.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boulangerie-jpg.webp 450w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boulangerie-300x200.webp 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                <\/div>\r\n                <div class=\"nt-listing-actus__item-infos\">\r\n                    <h3 class=\"nt-listing-actus__item-title\">Le novit\u00e0 di CSJ Emballages dopo il restyling del suo sito.<\/h3>\r\n                    <a href=\"https:\/\/www.csj-emballages.com\/it\/le-novita-di-csj-emballages-dopo-il-restyling-del-suo-sito\/\" class=\"nt-listing-actus__item-link\">\r\n                        Vedi altro                        <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                    <\/a>\r\n                <\/div>\r\n            <\/div>\r\n                    <div class=\"nt-listing-actus__item\">\r\n                <div class=\"nt-listing-actus__item-thumbnail\">\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"252\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boucherie-jpg.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boucherie-jpg.webp 450w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/emballage-boucherie-300x168.webp 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                <\/div>\r\n                <div class=\"nt-listing-actus__item-infos\">\r\n                    <h3 class=\"nt-listing-actus__item-title\">Scopri la nostra nuova gamma di imballaggi per la macelleria<\/h3>\r\n                    <a href=\"https:\/\/www.csj-emballages.com\/it\/scopri-la-nostra-nuova-gamma-di-imballaggi-per-la-macelleria\/\" class=\"nt-listing-actus__item-link\">\r\n                        Vedi altro                        <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                    <\/a>\r\n                <\/div>\r\n            <\/div>\r\n                    <div class=\"nt-listing-actus__item\">\r\n                <div class=\"nt-listing-actus__item-thumbnail\">\r\n                    <img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/nouveausite-jpg.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/nouveausite-jpg.webp 450w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/05\/nouveausite-300x200.webp 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>                <\/div>\r\n                <div class=\"nt-listing-actus__item-infos\">\r\n                    <h3 class=\"nt-listing-actus__item-title\">Un nuovo sito web per servirti al meglio<\/h3>\r\n                    <a href=\"https:\/\/www.csj-emballages.com\/it\/un-nuovo-sito-web-per-servirti-al-meglio\/\" class=\"nt-listing-actus__item-link\">\r\n                        Vedi altro                        <svg fill=\"none\" height=\"512\" viewBox=\"0 0 24 24\" width=\"512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g fill=\"rgb(0,0,0)\"><path d=\"m19 13h-14c-.6 0-1-.4-1-1s.4-1 1-1h14c.6 0 1 .4 1 1s-.4 1-1 1z\"\/><path d=\"m13 19c-.3 0-.5-.1-.7-.3-.4-.4-.4-1 0-1.4l6-6c.4-.4 1-.4 1.4 0s.4 1 0 1.4l-6 6c-.2.2-.4.3-.7.3z\"\/><path d=\"m19 13c-.3 0-.5-.1-.7-.3l-6-6c-.4-.4-.4-1 0-1.4s1-.4 1.4 0l6 6c.4.4.4 1 0 1.4-.2.2-.4.3-.7.3z\"\/><\/g><\/svg>                    <\/a>\r\n                <\/div>\r\n            <\/div>\r\n            <\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-653f06af e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con e-parent\" data-id=\"653f06af\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4465ba2f e-con-full e-flex e-con e-child\" data-id=\"4465ba2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4592afdc elementor-widget elementor-widget-image\" data-id=\"4592afdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"970\" height=\"638\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-14.22.27-e1714027089242.png\" class=\"attachment-large size-large wp-image-266700\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-14.22.27-e1714027089242.png 970w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-14.22.27-e1714027089242-300x197.png 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-14.22.27-e1714027089242-768x505.png 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-14.22.27-e1714027089242-600x395.png 600w\" sizes=\"(max-width: 970px) 100vw, 970px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30f1f8cf e-con-full e-flex e-con e-child\" data-id=\"30f1f8cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48f7905c elementor-widget elementor-widget-heading\" data-id=\"48f7905c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alimentari<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62c6b673 elementor-widget elementor-widget-text-editor\" data-id=\"62c6b673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u201cGli ingredienti culinari sono gli artigiani dei sapori, dando vita a ogni piatto con semplicit\u00e0 e delicatezza\u201d&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-520d274 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con-boxed e-con e-parent\" data-id=\"520d274\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a2da6f elementor-widget elementor-widget-spacer\" data-id=\"7a2da6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f27dee elementor-widget elementor-widget-spacer\" data-id=\"0f27dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c20c136 elementor-widget-divider--view-line_icon elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"c20c136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-utensils\" viewBox=\"0 0 416 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.9 15.2c.8 4.7 16.1 94.5 16.1 128.8 0 52.3-27.8 89.6-68.9 104.6L168 486.7c.7 13.7-10.2 25.3-24 25.3H80c-13.7 0-24.7-11.5-24-25.3l12.9-238.1C27.7 233.6 0 196.2 0 144 0 109.6 15.3 19.9 16.1 15.2 19.3-5.1 61.4-5.4 64 16.3v141.2c1.3 3.4 15.1 3.2 16 0 1.4-25.3 7.9-139.2 8-141.8 3.3-20.8 44.7-20.8 47.9 0 .2 2.7 6.6 116.5 8 141.8.9 3.2 14.8 3.4 16 0V16.3c2.6-21.6 44.8-21.4 48-1.1zm119.2 285.7l-15 185.1c-1.2 14 9.9 26 23.9 26h56c13.3 0 24-10.7 24-24V24c0-13.2-10.7-24-24-24-82.5 0-221.4 178.5-64.9 300.9z\"><\/path><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9b12e2 elementor-widget elementor-widget-heading\" data-id=\"d9b12e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Che cos\u2019\u00e8 il mondo alimentare?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26b329e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con-boxed e-con e-parent\" data-id=\"26b329e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25b9839 elementor-widget elementor-widget-text-editor\" data-id=\"25b9839\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #1c244b;\"><i>Da C.S.J Emballages, crediamo che la chiave per creare piatti memorabili risieda nella qualit\u00e0 degli ingredienti di base. Per questo siamo orgogliosi di offrirti una gamma eccezionale di basi culinarie, spezie semplici e composte, oltre a marinate, accuratamente selezionate per ispirare le tue creazioni in cucina. <\/i><\/span><\/p>\n<p><span style=\"color: #1c244b;\"><i>&nbsp;<\/i><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-abf39de e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con e-parent\" data-id=\"abf39de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9b72210 e-con-full e-flex e-con e-child\" data-id=\"9b72210\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7e171c elementor-widget elementor-widget-heading\" data-id=\"d7e171c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/?product_cat=bases-fonds-culinaires\">Le nostre basi \/ fondi culinari<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-367196f elementor-widget elementor-widget-text-editor\" data-id=\"367196f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le basi culinarie sono il punto di partenza perfetto per le tue ricette pi\u00f9 deliziose. Ricchi di sapori e aromi, questi fondi preparati con cura aggiungono una profondit\u00e0 impareggiabile ai tuoi piatti, siano essi classici o creativi. Che si tratti di un <a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/fondo-di-pollo-800-gr\/\">fondo di pollame<\/a> ricco e confortante, di un <a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/base-culinaria-brodo-di-verdure-900-g\/\">brodo vegetale<\/a> o di un <a href=\"https:\/\/www.csj-emballages.com\/it\/produit\/base-per-fumetto-di-pesce-800-gr\/\">fumetto di pesce<\/a>, le nostre basi culinarie sono il segreto degli chef per salse gustose. Dona alle tue creazioni culinarie un tocco di raffinatezza e complessit\u00e0 con le nostre basi culinarie di qualit\u00e0 superiore e risveglia i sensi dei tuoi ospiti a ogni assaggio.   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f656f9 e-con-full e-flex e-con e-child\" data-id=\"2f656f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9189fd1 elementor-widget elementor-widget-image\" data-id=\"9189fd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"587\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-16.01.02-e1714027383377.png\" class=\"attachment-large size-large wp-image-266704\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-16.01.02-e1714027383377.png 930w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-16.01.02-e1714027383377-300x189.png 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-16.01.02-e1714027383377-768x485.png 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-16.01.02-e1714027383377-600x379.png 600w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-64f854b e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con e-parent\" data-id=\"64f854b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a9a9a01 e-con-full e-flex e-con e-child\" data-id=\"a9a9a01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5877a72 elementor-widget elementor-widget-heading\" data-id=\"5877a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/\">Le nostre spezie semplici e composte<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-928fd0c elementor-widget elementor-widget-text-editor\" data-id=\"928fd0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esplora un mondo di sapori con la nostra vasta selezione di <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/spezie-semplici\/\">spezie semplici<\/a> e <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/spezie\/spezie-composte\/\">composte<\/a>, accuratamente miscelate per esaltare il gusto dei tuoi piatti. Che tu stia cercando mix classici o combinazioni esotiche per dare un tocco di originalit\u00e0 alle tue ricette, abbiamo tutto ci\u00f2 che ti serve per risvegliare le tue papille e stupire i tuoi ospiti. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11ec9fb e-con-full e-flex e-con e-child\" data-id=\"11ec9fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b63ece6 elementor-widget elementor-widget-image\" data-id=\"b63ece6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"592\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.22.40.png\" class=\"attachment-large size-large wp-image-266702\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.22.40.png 930w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.22.40-300x191.png 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.22.40-768x489.png 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.22.40-600x382.png 600w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a852ee7 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con e-parent\" data-id=\"a852ee7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-08d9e1c e-con-full e-flex e-con e-child\" data-id=\"08d9e1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-860d8c4 elementor-widget elementor-widget-heading\" data-id=\"860d8c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/marinature\/\">Le nostre marinate<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b62d4a7 elementor-widget elementor-widget-text-editor\" data-id=\"b62d4a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dai a carni e pesci un\u2019esplosione di sapori con le nostre marinate gustose. Dalle ricette tradizionali alle creazioni originali, le nostre <a href=\"https:\/\/www.csj-emballages.com\/it\/categorie-produit\/alimentari\/marinature\/\">marinate<\/a> sono pensate per impregnare i tuoi ingredienti di sapori deliziosi. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3261440 e-con-full e-flex e-con e-child\" data-id=\"3261440\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49db499 elementor-widget elementor-widget-image\" data-id=\"49db499\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"592\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.55.49.png\" class=\"attachment-large size-large wp-image-266703\" alt=\"\" srcset=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.55.49.png 930w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.55.49-300x191.png 300w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.55.49-768x489.png 768w, https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/04\/Capture-decran-2024-04-24-a-15.55.49-600x382.png 600w\" sizes=\"(max-width: 930px) 100vw, 930px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de65177 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-hidden-laptop elementor-hidden-tablet_extra e-flex e-con-boxed e-con e-parent\" data-id=\"de65177\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6818378 elementor-widget elementor-widget-spacer\" data-id=\"6818378\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c10d58e elementor-widget elementor-widget-heading\" data-id=\"c10d58e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra selezione di prodotti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"woocommerce elementor-element elementor-element-54d67bf elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-loop-carousel\" data-id=\"54d67bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:267477,&quot;_skin&quot;:&quot;product&quot;,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;speed&quot;:2000,&quot;slides_to_show_laptop&quot;:&quot;3&quot;,&quot;slides_to_show_tablet_extra&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-loop-container&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;offset_sides&quot;:&quot;none&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.product\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper elementor-loop-container elementor-grid\" role=\"list\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t<style id=\"loop-267477\">.elementor-267477 .elementor-element.elementor-element-eb0c916{--display:flex;}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"267477\" class=\"elementor elementor-267477 elementor-4958 elementor-4958 swiper-slide e-loop-item e-loop-item-288835 post-288835 product type-product status-publish has-post-thumbnail product_cat-imballaggi-alimentari product_cat-panetteria-pasticceria product_cat-sacchetti product_cat-sacchetti-per-croissant product_cat-sacchi-sacchetti-e-carte first instock taxable shipping-taxable purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eb0c916 e-flex e-con-boxed e-con e-parent\" data-id=\"eb0c916\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36f890f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"36f890f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.07.04-e1711548453242.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Laurier moulu en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/complet-chair-avec-piment-d-espelette-2-kg-jpg-e1712137293788.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.17.04-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.17.04-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.17.05-e1711545455124.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/couscous-epice-pas-cher-discount-csj-emballages-zoom-2-jpg-e1711542911640.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.21.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.21.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview-150x150.png\" alt=\"marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.26.29-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.26.29-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.24.33-e1711545898429.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview-150x150.png\" alt=\"marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-2-2-150x150.webp\" alt=\"Marinade Piment Espelette 5 kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.14.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.14.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-1-150x150.webp\" alt=\"marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.37.30-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.37.30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cannelle-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Cannelle extrafine moulue 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.30.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.30.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/1479162_378036-2-removebg-preview-150x150.png\" alt=\"1479162_378036-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.01.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.01.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir grain 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.58.51-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.58.51-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.35.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.35.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.47.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.47.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Laurier feuilles en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-moulue-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Clou de girofle moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/chorizo-epice-pas-cher-discount-csj-emballages-big-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.57.52-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.57.52\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/herbe-de-provence-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"herbe-de-provence-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.18.00-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.18.00-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/thym-moulu-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"thym-moulu-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_10.17.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_10.17.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"origan-feuille-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"40 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.39.31-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.39.31-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"41 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poulet-grill-3033-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"42 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1-150x150.webp\" alt=\"saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"43 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-aux-herbe-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"44 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.37.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.37.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"45 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/echalote-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"echalote-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"46 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.56.38-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.56.38\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"47 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/ciboulette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"ciboulette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"48 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curry-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"curry-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"49 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"50 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.47.59-e1711547309473.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"51 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/andouilette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"andouilette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"52 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.03.28-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.03.28-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"53 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"54 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.01.11-e1711548107741.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"55 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"56 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"origan-moulue-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"57 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.11.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.11.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"58 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir moulu 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"59 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.26.56-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.26.56-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"60 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/noix-de-muscade-poudre-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Noix de muscade 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"61 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-fraiche-campagnarde-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"62 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.07.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.07.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"63 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Clou de girofle grain\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"64 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.49.38-e1711547400171.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"65 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"66 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.14.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.14.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"67 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.10.07-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.10.07-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"68 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curcumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Curcuma rhizome madras moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"69 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-11.46.15-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 11.46.15\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"267477\" class=\"elementor elementor-267477 elementor-4958 elementor-4958 swiper-slide e-loop-item e-loop-item-287451 post-287451 product type-product status-publish has-post-thumbnail product_cat-igiene-e-manutenzione product_cat-sacchi-immondizia  instock taxable shipping-taxable purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eb0c916 e-flex e-con-boxed e-con e-parent\" data-id=\"eb0c916\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36f890f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"36f890f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.07.04-e1711548453242.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Laurier moulu en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/complet-chair-avec-piment-d-espelette-2-kg-jpg-e1712137293788.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.17.04-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.17.04-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.17.05-e1711545455124.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/couscous-epice-pas-cher-discount-csj-emballages-zoom-2-jpg-e1711542911640.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.21.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.21.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview-150x150.png\" alt=\"marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.26.29-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.26.29-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.24.33-e1711545898429.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview-150x150.png\" alt=\"marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-2-2-150x150.webp\" alt=\"Marinade Piment Espelette 5 kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.14.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.14.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-1-150x150.webp\" alt=\"marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.37.30-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.37.30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cannelle-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Cannelle extrafine moulue 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.30.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.30.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/1479162_378036-2-removebg-preview-150x150.png\" alt=\"1479162_378036-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.01.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.01.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir grain 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.58.51-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.58.51-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.35.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.35.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.47.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.47.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Laurier feuilles en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-moulue-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Clou de girofle moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/chorizo-epice-pas-cher-discount-csj-emballages-big-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.57.52-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.57.52\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/herbe-de-provence-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"herbe-de-provence-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.18.00-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.18.00-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/thym-moulu-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"thym-moulu-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_10.17.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_10.17.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"origan-feuille-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"40 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.39.31-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.39.31-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"41 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poulet-grill-3033-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"42 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1-150x150.webp\" alt=\"saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"43 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-aux-herbe-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"44 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.37.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.37.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"45 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/echalote-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"echalote-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"46 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.56.38-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.56.38\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"47 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/ciboulette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"ciboulette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"48 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curry-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"curry-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"49 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"50 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.47.59-e1711547309473.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"51 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/andouilette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"andouilette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"52 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.03.28-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.03.28-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"53 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"54 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.01.11-e1711548107741.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"55 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"56 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"origan-moulue-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"57 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.11.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.11.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"58 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir moulu 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"59 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.26.56-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.26.56-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"60 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/noix-de-muscade-poudre-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Noix de muscade 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"61 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-fraiche-campagnarde-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"62 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.07.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.07.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"63 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Clou de girofle grain\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"64 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.49.38-e1711547400171.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"65 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"66 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.14.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.14.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"67 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.10.07-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.10.07-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"68 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curcumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Curcuma rhizome madras moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"69 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-11.46.15-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 11.46.15\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"267477\" class=\"elementor elementor-267477 elementor-4958 elementor-4958 swiper-slide e-loop-item e-loop-item-287422 post-287422 product type-product status-publish has-post-thumbnail product_cat-igiene-e-manutenzione product_cat-sacchi-immondizia  instock taxable shipping-taxable purchasable product-type-simple\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-eb0c916 e-flex e-con-boxed e-con e-parent\" data-id=\"eb0c916\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36f890f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"36f890f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.07.04-e1711548453242.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Laurier moulu en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/complet-chair-avec-piment-d-espelette-2-kg-jpg-e1712137293788.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.17.04-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.17.04-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Saumure-jambon-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.17.05-e1711545455124.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"baies-de-genievre-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/couscous-epice-pas-cher-discount-csj-emballages-zoom-2-jpg-e1711542911640.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.21.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.21.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"basilic-feuille-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview-150x150.png\" alt=\"marinade-epice-thym-romarin-alimentaire-eylan-viande-legume-csj-emballages-z-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.26.29-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.26.29-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"romarin-feuille-couppees-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.24.33-e1711545898429.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview-150x150.png\" alt=\"marinade-epice-texas-alimentaire-eylan-viande-legume-csj-emballages-big-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-2-2-150x150.webp\" alt=\"Marinade Piment Espelette 5 kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.14.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.14.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-moulur-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag-1-150x150.webp\" alt=\"marinade-epice-piment-espelette-alimentaire-eylan-viande-legume-csj-emballag\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.37.30-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.37.30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cannelle-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Cannelle extrafine moulue 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.30.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.30.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/1479162_378036-2-removebg-preview-150x150.png\" alt=\"1479162_378036-2-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.01.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.01.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir grain 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.58.51-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.58.51-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.35.57-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.35.57-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.47.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.47.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/laurier-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Laurier feuilles en 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-moulue-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"Clou de girofle moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/chorizo-epice-pas-cher-discount-csj-emballages-big-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.57.52-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.57.52\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/herbe-de-provence-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"herbe-de-provence-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.18.00-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.18.00-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/thym-moulu-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"thym-moulu-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"saucisson-cuit-ail-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_10.17.02-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_10.17.02-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"39 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-feuille-epice-pas-cher-discount-csj-emballages-big-150x150.webp\" alt=\"origan-feuille-epice-pas-cher-discount-csj-emballages-big\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"40 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-22_a_16.39.31-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-22_\u00e0_16.39.31-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"41 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poulet-grill-3033-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"42 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1-150x150.webp\" alt=\"saucisse-halla-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"43 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-aux-herbe-flamboyante-epice-pas-cher-discount-csj-emballages-zoom-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"44 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.37.22-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.37.22-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"45 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/echalote-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"echalote-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"46 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.56.38-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 14.56.38\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"47 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/ciboulette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"ciboulette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"48 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curry-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"curry-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"49 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"piment-doux-cascaraepice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"50 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.47.59-e1711547309473.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"51 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/andouilette-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"andouilette-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"52 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.03.28-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.03.28-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"53 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/cumin-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"cumin-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"54 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-15.01.11-e1711548107741.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"55 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/coriande-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"coriande-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"56 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/origan-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"origan-moulue-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"57 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.11.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.11.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"58 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/poivre-noir-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Poivre noir moulu 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"59 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_11.26.56-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_11.26.56-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"60 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/noix-de-muscade-poudre-moulue-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Noix de muscade 1kg\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"61 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/saucisse-fraiche-campagnarde-epice-pas-cher-discount-csj-emballages-zoom-1-jpg.webp\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"62 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.07.13-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.07.13-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"63 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/clou-de-girofle-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Clou de girofle grain\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"64 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-14.49.38-e1711547400171.png\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"65 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"gimgembre-moulu-epice-pas-cher-discount-csj-emballages-zoom\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"66 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-03-27_a_12.14.20-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-03-27_\u00e0_12.14.20-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"67 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture_d_ecran_2024-04-03_a_08.10.07-removebg-preview-150x150.png\" alt=\"Capture_d_\u00e9cran_2024-04-03_\u00e0_08.10.07-removebg-preview\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"68 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/curcumin-moulur-epice-pas-cher-discount-csj-emballages-zoom-150x150.webp\" alt=\"Curcuma rhizome madras moulu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"69 di 69\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/03\/Capture-decran-2024-03-27-a-11.46.15-150x150.png\" alt=\"Capture d\u2019\u00e9cran 2024-03-27 \u00e0 11.46.15\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CSJ alimentari CSJ alimentari mette l\u2019accento sulla qualit\u00e0 degli ingredienti di base per piatti indimenticabili. La nostra gamma comprende basi culinarie, spezie semplici e composte, conserve, budelli e marinate, selezionate appositamente per stimolare la tua creativit\u00e0 in cucina. Le nostre promozioni La nostra selezione Le nostre novit\u00e0 Ajouter \u00e0 ma liste -30% R\u00e9f : 10465 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":266706,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-266696","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alimentari<\/title>\n<meta name=\"description\" content=\"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondo alimentare\" \/>\n<meta property=\"og:description\" content=\"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/csjemballages\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T05:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/\",\"name\":\"Alimentari\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp\",\"datePublished\":\"2024-04-12T13:46:14+00:00\",\"dateModified\":\"2026-04-27T05:46:03+00:00\",\"description\":\"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp\",\"width\":300,\"height\":300,\"caption\":\"Alimentation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondo alimentare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alimentari","description":"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/","og_locale":"it_IT","og_type":"article","og_title":"Mondo alimentare","og_description":"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.","og_url":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/","og_site_name":"CSJ Emballages","article_publisher":"https:\/\/www.facebook.com\/csjemballages","article_modified_time":"2026-04-27T05:46:03+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/","url":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/","name":"Alimentari","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp","datePublished":"2024-04-12T13:46:14+00:00","dateModified":"2026-04-27T05:46:03+00:00","description":"Scopri il nostro mondo Alimentari, dove ti proponiamo conserve, marinate, budelli e prodotti alimentari di qualit\u00e0.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#primaryimage","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2024\/10\/Design-sans-titre-8-jpg-e1727969477405.webp","width":300,"height":300,"caption":"Alimentation"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/it\/mondo-alimentare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.csj-emballages.com\/it\/universo-imballaggi-alimentari\/"},{"@type":"ListItem","position":2,"name":"Mondo alimentare"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/it\/#website","url":"https:\/\/www.csj-emballages.com\/it\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/it\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/pages\/266696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/comments?post=266696"}],"version-history":[{"count":21,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/pages\/266696\/revisions"}],"predecessor-version":[{"id":278606,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/pages\/266696\/revisions\/278606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media\/266706"}],"wp:attachment":[{"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/media?parent=266696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/categories?post=266696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/it\/wp-json\/wp\/v2\/tags?post=266696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}