{"id":2114,"count":1,"description":"","link":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/","name":"Bobinas industriales","slug":"bobinas-industriales","taxonomy":"product_cat","parent":1388,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bobinas industriales<\/title>\n<meta name=\"description\" content=\"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Bobinas industriales\" \/>\n<meta property=\"og:description\" content=\"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/\",\"url\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/\",\"name\":\"Bobinas industriales\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#website\"},\"description\":\"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.csj-emballages.com\/es\/universo-del-envasado-alimentario\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Higiene y mantenimiento\",\"item\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Limpiar\",\"item\":\"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Bobinas industriales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/es\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bobinas industriales","description":"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Bobinas industriales","og_description":"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.","og_url":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/","og_site_name":"CSJ Emballages","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/","url":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/","name":"Bobinas industriales","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/es\/#website"},"description":"Descubra nuestra gama de enrolladores industriales de gamuza o guata pura. Adaptadas a diferentes necesidades y entornos.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/bobinas-industriales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.csj-emballages.com\/es\/universo-del-envasado-alimentario\/"},{"@type":"ListItem","position":2,"name":"Higiene y mantenimiento","item":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/"},{"@type":"ListItem","position":3,"name":"Limpiar","item":"https:\/\/www.csj-emballages.com\/es\/categorie-produit\/higiene-y-mantenimiento\/limpiar\/"},{"@type":"ListItem","position":4,"name":"Bobinas industriales"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/es\/#website","url":"https:\/\/www.csj-emballages.com\/es\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/es\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.csj-emballages.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/02\/bobine-blanche.webp","_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/es\/wp-json\/wp\/v2\/product_cat\/2114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/es\/wp-json\/wp\/v2\/product_cat\/1388"}],"wp:post_type":[{"href":"https:\/\/www.csj-emballages.com\/es\/wp-json\/wp\/v2\/product?product_cat=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}