{"id":8613,"count":2,"description":"","link":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/","name":"Uncategorized","slug":"non-classe-en","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Uncategorized - CSJ Emballages<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Uncategorized\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/\",\"url\":\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/\",\"name\":\"Archives des Uncategorized - CSJ Emballages\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.csj-emballages.com\/en\/food-packaging-universe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/en\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives des Uncategorized - CSJ Emballages","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Uncategorized","og_url":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/","og_site_name":"CSJ Emballages","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/","url":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/","name":"Archives des Uncategorized - CSJ Emballages","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/en\/categorie-produit\/non-classe-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.csj-emballages.com\/en\/food-packaging-universe\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/en\/#website","url":"https:\/\/www.csj-emballages.com\/en\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/en\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.csj-emballages.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.png","_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/en\/wp-json\/wp\/v2\/product_cat\/8613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.csj-emballages.com\/en\/wp-json\/wp\/v2\/product?product_cat=8613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}