{"id":227008,"date":"2025-03-08T02:18:55","date_gmt":"2025-03-08T01:18:55","guid":{"rendered":"https:\/\/www.csj-emballages.com\/?post_type=product&#038;p=227008"},"modified":"2026-06-27T02:14:12","modified_gmt":"2026-06-27T00:14:12","slug":"thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500","status":"publish","type":"product","link":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/","title":{"rendered":"Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500"},"content":{"rendered":"<h2>Aufschnittbeutel<\/h2>\n<hr>\n<h3>Beschreibung von unserem Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500<\/h3>\n<p><!--more--><\/p>\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-12\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 px-6\">\n<div class=\"mx-auto flex flex-1 text-base gap-4 md:gap-5 lg:gap-6 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn @xs\/thread:px-0 @sm\/thread:px-1.5 @md\/thread:px-4\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"04080541-7628-4997-9580-4b4b174b20cc\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark\">\n<p data-start=\"0\" data-end=\"1749\">Optimieren Sie die Lagerung und Pr\u00e4sentation Ihrer Produkte mit diesem <strong>wei\u00dfen Thermoschinkenbeutel von 25 x 33 cm<\/strong>. Er wurde entwickelt, um den Anforderungen von Fachleuten wie Metzgern, Fleischern und Caterern gerecht zu werden, und gew\u00e4hrleistet einen guten Schutz der Lebensmittel vor Luft, Feuchtigkeit und \u00e4u\u00dferen Verunreinigungen. Ideal f\u00fcr die <strong>Verpackung von<\/strong> <strong>geschnittenen Wurstwaren<\/strong>, Aufschnitt und anderen Produkten, die eine sorgf\u00e4ltige Lagerung erfordern, garantiert er eine sichere Aufbewahrung und bewahrt gleichzeitig die Frische und den Geschmack der Lebensmittel. Sein <strong>Thermo<\/strong>-Material gew\u00e4hrleistet eine erh\u00f6hte Best\u00e4ndigkeit gegen\u00fcber Temperaturschwankungen, wodurch das Risiko von Kondensation oder Produktver\u00e4nderungen begrenzt wird. Sein Format von <strong>25 x 33<\/strong> <strong>cm<\/strong> ist perfekt f\u00fcr gro\u00dfe Portionen geeignet und erleichtert die Handhabung und Lagerung in der Vitrine oder im K\u00fchlraum.    <\/p>\n<p data-start=\"0\" data-end=\"1749\"><!--more--><\/p>\n<p data-start=\"0\" data-end=\"1749\">Dank ihres klaren und professionellen Designs wertet diese <strong>selbstklebende Wursth\u00fclle<\/strong> das Produkt auf und st\u00e4rkt gleichzeitig das Markenimage von Einzelh\u00e4ndlern, die Wert auf eine hochwertige Verpackung legen. Die praktische Anwendung vereinfacht das Verpacken und optimiert so die Arbeitszeit im Gesch\u00e4ft oder im Labor. Sie ist zuverl\u00e4ssig und widerstandsf\u00e4hig, verhindert das Auslaufen von Fl\u00fcssigkeiten und garantiert einen sicheren Transport, der ein versehentliches \u00d6ffnen verhindert. Sie ist eine moderne und effiziente Alternative zu herk\u00f6mmlichen Verpackungen und erf\u00fcllt die strengsten Hygienevorschriften. Kurzum, sie ist ideal f\u00fcr den Verkauf zum Mitnehmen, die Lagerung im Regal oder die Aufbewahrung zu Hause. Diese Tasche vereint Zweckm\u00e4\u00dfigkeit, Sicherheit und \u00c4sthetik und bietet eine optimale L\u00f6sung f\u00fcr anspruchsvolle Fachleute und Privatpersonen, die ihre Lebensmittel unter den besten Bedingungen aufbewahren m\u00f6chten.    <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<p data-start=\"108\" data-end=\"487\"><!--more--><\/p>\n<h4>Ihre Vorteile :<\/h4>\n<ul>\n<li data-start=\"634\" data-end=\"738\"><strong data-start=\"636\" data-end=\"660\">Lebensmittelsicherheit<\/strong>: Sch\u00fctzt wirksam vor Feuchtigkeit und Verunreinigungen von au\u00dfen.<\/li>\n<li data-start=\"839\" data-end=\"936\"><strong data-start=\"841\" data-end=\"863\">Praktisch und schnell<\/strong>: Einfach zu verwenden f\u00fcr eine professionelle Verpackung mit nur einem Handgriff.<\/li>\n<li data-start=\"937\" data-end=\"1018\"><strong data-start=\"939\" data-end=\"954\">Vielseitig<\/strong> einsetzbar : Geeignet f\u00fcr Wurst, Fleisch und andere frische Produkte.<\/li>\n<li data-start=\"1019\" data-end=\"1110\"><strong data-start=\"1021\" data-end=\"1048\">Schlichtes und elegantes Design<\/strong>: Wei\u00dfe Aufschnittmappe f\u00fcr eine saubere und gepflegte Pr\u00e4sentation.<\/li>\n<li><strong>2 Verschlussm\u00f6glichkeiten<\/strong>: Mit integriertem Klebestreifen oder durch Hei\u00dfsiegelung<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h4>Weitere Informationen :<\/h4>\n<ul>\n<li><strong>Verpackung<\/strong>: Karton mit 500 St\u00fcck<\/li>\n<li><strong>Ma\u00dfe<\/strong>: 25 x 33 cm<\/li>\n<li><strong>Material<\/strong>: Papier<\/li>\n<li><strong>Farbe<\/strong>: Wei\u00df \/ Rosa<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>Dieses Produkt ist in verschiedenen Gr\u00f6\u00dfen erh\u00e4ltlich : <span style=\"color: #d12727;\"><a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/es\/produit\/bolsa-termica-blanca-con-impresion-de-charcuteria-25-x-166-cm-paquete-de-1000\/\">25 x 16,6 cm<\/a><\/span> \/ <span style=\"color: #d12727;\"><a style=\"color: #d12727;\" href=\"https:\/\/www.csj-emballages.com\/es\/produit\/bolsa-termica-blanca-con-impresion-de-charcuteria-25-x-25-cm-por-1000\/\">25 x 25 cm<\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><a href=\"https:\/\/www.csj-emballages.com\/de\/categorie-produit\/lebensmittelverpackungen\/metzgerei-und-feinkostgeschaft\/lebensmittelpapier\/selbstklebende-hullen\/\">Sehen Sie sich den Rest unseres Sortiments an selbstklebenden H\u00fcllen an<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufschnittbeutel Beschreibung von unserem Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500<\/p>\n","protected":false},"featured_media":227231,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1137,1170,2571,9262],"product_tag":[],"class_list":{"0":"post-227008","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-lebensmittelverpackungen","7":"product_cat-metzgerei-und-feinkostgeschaft","8":"product_cat-lebensmittelpapier","9":"product_cat-selbstklebende-hullen","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v26.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aufschnittbeutel Thermo Wei\u00df 25 x 33 cm pro 500<\/title>\n<meta name=\"description\" content=\"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500\" \/>\n<meta property=\"og:description\" content=\"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/\" \/>\n<meta property=\"og:site_name\" content=\"CSJ Emballages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/csjemballages\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-27T00:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/\",\"url\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/\",\"name\":\"Aufschnittbeutel Thermo Wei\u00df 25 x 33 cm pro 500\",\"isPartOf\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp\",\"datePublished\":\"2025-03-08T01:18:55+00:00\",\"dateModified\":\"2026-06-27T00:14:12+00:00\",\"description\":\"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp\",\"width\":800,\"height\":800,\"caption\":\"pochette charcuterie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.csj-emballages.com\/de\/universum-lebensmittelverpackungen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.csj-emballages.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#website\",\"url\":\"https:\/\/www.csj-emballages.com\/de\/\",\"name\":\"CSJ Emballages\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.csj-emballages.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#Organization\/\",\"name\":\"CSJ Emballages\",\"url\":\"https:\/\/www.csj-emballages.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"contentUrl\":\"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp\",\"width\":250,\"height\":95,\"caption\":\"CSJ Emballages\"},\"image\":{\"@id\":\"https:\/\/www.csj-emballages.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/csjemballages\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"ZI La Lechere\",\"addressLocality\":\"Patornay\",\"postalCode\":\"39130\",\"addressCountry\":\"FR\"},\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"Service client\",\"telephone\":\"0384254272\",\"email\":\"contact@csj-emballages.com\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aufschnittbeutel Thermo Wei\u00df 25 x 33 cm pro 500","description":"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/","og_locale":"de_DE","og_type":"article","og_title":"Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500","og_description":"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.","og_url":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/","og_site_name":"CSJ Emballages","article_publisher":"https:\/\/www.facebook.com\/csjemballages","article_modified_time":"2026-06-27T00:14:12+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/","url":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/","name":"Aufschnittbeutel Thermo Wei\u00df 25 x 33 cm pro 500","isPartOf":{"@id":"https:\/\/www.csj-emballages.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage"},"image":{"@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage"},"thumbnailUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp","datePublished":"2025-03-08T01:18:55+00:00","dateModified":"2026-06-27T00:14:12+00:00","description":"Wei\u00dfe Thermo-Wursth\u00fclle 25 x 33 cm (Packung zu 500). Perfekt f\u00fcr die optimale Aufbewahrung von Wurst- und Fleischwaren.","breadcrumb":{"@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#primaryimage","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie.webp","width":800,"height":800,"caption":"pochette charcuterie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.csj-emballages.com\/de\/produit\/thermotasche-weis-bedruckt-wurstwaren-25-x-33-cm-pro-500\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.csj-emballages.com\/de\/universum-lebensmittelverpackungen\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.csj-emballages.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Aufschnittbeutel Thermo wei\u00df 25 x 33 cm pro 500"}]},{"@type":"WebSite","@id":"https:\/\/www.csj-emballages.com\/de\/#website","url":"https:\/\/www.csj-emballages.com\/de\/","name":"CSJ Emballages","description":"","publisher":{"@id":"https:\/\/www.csj-emballages.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.csj-emballages.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.csj-emballages.com\/de\/#Organization\/","name":"CSJ Emballages","url":"https:\/\/www.csj-emballages.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.csj-emballages.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","contentUrl":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2023\/10\/logo_csj.webp","width":250,"height":95,"caption":"CSJ Emballages"},"image":{"@id":"https:\/\/www.csj-emballages.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/csjemballages"],"address":{"@type":"PostalAddress","streetAddress":"ZI La Lechere","addressLocality":"Patornay","postalCode":"39130","addressCountry":"FR"},"contactPoint":[{"@type":"ContactPoint","contactType":"Service client","telephone":"0384254272","email":"contact@csj-emballages.com"}]}]}},"df_price":50.23,"df_sale_price":"","df_regular_price":50.23,"df_image_link":"https:\/\/www.csj-emballages.com\/wp-content\/uploads\/2025\/03\/pochette-charcuterie-300x300.webp","tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_percentage_rules":[],"tiered_pricing_minimum":1,"tiered_pricing_roles_data":[],"_links":{"self":[{"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/product\/227008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/media\/227231"}],"wp:attachment":[{"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/media?parent=227008"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/product_brand?post=227008"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/product_cat?post=227008"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.csj-emballages.com\/de\/wp-json\/wp\/v2\/product_tag?post=227008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}